{"id":7,"date":"2025-06-01T14:27:42","date_gmt":"2025-06-01T12:27:42","guid":{"rendered":"https:\/\/btcmodels.com\/model-demo\/?page_id=7"},"modified":"2025-06-01T14:27:42","modified_gmt":"2025-06-01T12:27:42","slug":"home","status":"publish","type":"page","link":"https:\/\/btcmodels.com\/model-demo\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-btcmodels-json.php","meta":{"footnotes":""},"class_list":["post-7","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":1,"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":8,"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/pages\/7\/revisions\/8"}],"wp:attachment":[{"href":"https:\/\/btcmodels.com\/model-demo\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}